{"id":17,"count":4,"description":"","link":"https:\/\/www.ecorenov.ca\/en\/contractor\/mold\/prevention\/","name":"Mold Prevention","slug":"prevention","taxonomy":"category","parent":6,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mold Prevention (1\/1) | EcoRenov<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mold Prevention (1\/1) | EcoRenov\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecorenov.ca\/en\/contractor\/mold\/prevention\/\" \/>\n<meta property=\"og:site_name\" content=\"Mold Removal &amp; Asbestos Remediation EcoRenov\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.ecorenov.ca\\\/en\\\/contractor\\\/mold\\\/prevention\\\/\",\"url\":\"https:\\\/\\\/www.ecorenov.ca\\\/en\\\/contractor\\\/mold\\\/prevention\\\/\",\"name\":\"Mold Prevention (1\\\/1) | EcoRenov\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecorenov.ca\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ecorenov.ca\\\/en\\\/contractor\\\/mold\\\/prevention\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ecorenov.ca\\\/en\\\/contractor\\\/mold\\\/prevention\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"EcoRenov\",\"item\":\"https:\\\/\\\/www.ecorenov.ca\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mold Removal &amp; Mold Remediation\",\"item\":\"https:\\\/\\\/www.ecorenov.ca\\\/en\\\/contractor\\\/mold\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mold Prevention\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecorenov.ca\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ecorenov.ca\\\/en\\\/\",\"name\":\"Mold Removal &amp; Asbestos Remediation EcoRenov\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ecorenov.ca\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecorenov.ca\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ecorenov.ca\\\/en\\\/#organization\",\"name\":\"EcoRenov\",\"url\":\"https:\\\/\\\/www.ecorenov.ca\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/www.ecorenov.ca\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ecorenov.ca\\\/en\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Mold-removal-asbestos-remediation-EcoRenov.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ecorenov.ca\\\/en\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Mold-removal-asbestos-remediation-EcoRenov.jpg\",\"width\":295,\"height\":86,\"caption\":\"EcoRenov\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ecorenov.ca\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mold Prevention (1\/1) | EcoRenov","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Mold Prevention (1\/1) | EcoRenov","og_url":"https:\/\/www.ecorenov.ca\/en\/contractor\/mold\/prevention\/","og_site_name":"Mold Removal &amp; Asbestos Remediation EcoRenov","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.ecorenov.ca\/en\/contractor\/mold\/prevention\/","url":"https:\/\/www.ecorenov.ca\/en\/contractor\/mold\/prevention\/","name":"Mold Prevention (1\/1) | EcoRenov","isPartOf":{"@id":"https:\/\/www.ecorenov.ca\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.ecorenov.ca\/en\/contractor\/mold\/prevention\/#breadcrumb"},"inLanguage":"en-CA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecorenov.ca\/en\/contractor\/mold\/prevention\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"EcoRenov","item":"https:\/\/www.ecorenov.ca\/en\/"},{"@type":"ListItem","position":2,"name":"Mold Removal &amp; Mold Remediation","item":"https:\/\/www.ecorenov.ca\/en\/contractor\/mold\/"},{"@type":"ListItem","position":3,"name":"Mold Prevention"}]},{"@type":"WebSite","@id":"https:\/\/www.ecorenov.ca\/en\/#website","url":"https:\/\/www.ecorenov.ca\/en\/","name":"Mold Removal &amp; Asbestos Remediation EcoRenov","description":"","publisher":{"@id":"https:\/\/www.ecorenov.ca\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecorenov.ca\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/www.ecorenov.ca\/en\/#organization","name":"EcoRenov","url":"https:\/\/www.ecorenov.ca\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/www.ecorenov.ca\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecorenov.ca\/en\/wp-content\/uploads\/2020\/03\/Mold-removal-asbestos-remediation-EcoRenov.jpg","contentUrl":"https:\/\/www.ecorenov.ca\/en\/wp-content\/uploads\/2020\/03\/Mold-removal-asbestos-remediation-EcoRenov.jpg","width":295,"height":86,"caption":"EcoRenov"},"image":{"@id":"https:\/\/www.ecorenov.ca\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ecorenov.ca\/en\/wp-json\/wp\/v2\/categories\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecorenov.ca\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.ecorenov.ca\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.ecorenov.ca\/en\/wp-json\/wp\/v2\/categories\/6"}],"wp:post_type":[{"href":"https:\/\/www.ecorenov.ca\/en\/wp-json\/wp\/v2\/posts?categories=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}